{"id":13,"date":"2022-05-11T11:00:17","date_gmt":"2022-05-11T11:00:17","guid":{"rendered":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/?page_id=13"},"modified":"2024-10-01T16:28:58","modified_gmt":"2024-10-01T16:28:58","slug":"ief-comfya","status":"publish","type":"page","link":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/","title":{"rendered":"IEF | COMFYA"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.17.3&#8243; background_color=\u00bbrgba(255,255,255,0)\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb transparent_background=\u00bbon\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_slider show_image_video_mobile=\u00bbon\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbPortada (Deslizador)\u00bb module_class=\u00bbpagina-texto-light\u00bb _builder_version=\u00bb4.17.3&#8243; header_level=\u00bbh1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb46px\u00bb body_font=\u00bbLato||on||||||\u00bb body_font_size=\u00bb30px\u00bb background_blend=\u00bbmultiply\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb40px\u00bb button_font=\u00bb||||||||\u00bb text_orientation=\u00bbleft\u00bb custom_padding=\u00bb|||\u00bb header_text_shadow_style=\u00bbpreset3&#8243; body_text_shadow_style=\u00bbpreset3&#8243; box_shadow_style=\u00bbpreset6&#8243; box_shadow_blur=\u00bb10px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb box_shadow_style_button=\u00bbpreset3&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][et_pb_slide heading=\u00bbUn espacio para ti\u00bb button_text=\u00bb\u00daltimas novedades\u00bb button_link=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/#Destacado\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-Comfya-1.png\u00bb use_bg_overlay=\u00bbon\u00bb bg_overlay_color=\u00bbrgba(198,198,198,0.81)\u00bb _builder_version=\u00bb4.17.3&#8243; body_font=\u00bb||||||||\u00bb background_color=\u00bb#afafaf\u00bb background_color_gradient_direction=\u00bb223deg\u00bb background_image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/noticia_camino-de-Santiago_18_06_16_Los-caminante-llegan-a-Santiago_2-min.jpg\u00bb background_blend=\u00bbluminosity\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb23px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#ffffff\u00bb button_border_radius=\u00bb100px\u00bb button_font=\u00bbLato||on||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb body_text_shadow_style__hover=\u00bbnone\u00bb body_text_shadow_style__hover_enabled=\u00bbnone\u00bb body_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb body_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>Ven y ver\u00e1s&#8230;<\/p>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bbM\u00faltiples ramas\u00bb button_text=\u00bbDescubre el MJS en Alicante\u00bb button_link=\u00bbhttps:\/\/alicante.salesianos.edu\/mjs\/\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/logo_movimiento_juvenil_salesiano_portada-min.png\u00bb use_bg_overlay=\u00bboff\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bbrgba(216,216,216,0.57)\u00bb background_image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/portada_arbol_mjs-min.jpg\u00bb background_blend=\u00bbhue\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb23px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#f22148&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_font=\u00bbLato||on||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb body_text_shadow_style__hover=\u00bbnone\u00bb body_text_shadow_style__hover_enabled=\u00bbnone\u00bb body_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb body_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>Mismas raices<\/p>\n<p>[\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bbrgba(255,255,255,0)\u00bb custom_padding=\u00bb0px|0px|0px|0px\u00bb transparent_background=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_slider show_image_video_mobile=\u00bbon\u00bb admin_label=\u00bbPortada (Deslizador)\u00bb module_class=\u00bbpagina-texto-light\u00bb _builder_version=\u00bb4.17.3&#8243; header_level=\u00bbh1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb46px\u00bb body_font=\u00bbLato||on||||||\u00bb body_font_size=\u00bb30px\u00bb background_blend=\u00bbmultiply\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb40px\u00bb button_font=\u00bb||||||||\u00bb custom_padding=\u00bb|||\u00bb header_text_shadow_style=\u00bbpreset3&#8243; body_text_shadow_style=\u00bbpreset3&#8243; box_shadow_style=\u00bbpreset6&#8243; box_shadow_blur=\u00bb10px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb box_shadow_style_button=\u00bbpreset3&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][et_pb_slide heading=\u00bbUn espacio para ti\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-Comfya-1.png\u00bb use_bg_overlay=\u00bbon\u00bb bg_overlay_color=\u00bbrgba(198,198,198,0.81)\u00bb heading_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.17.3&#8243; body_font=\u00bb||||||||\u00bb background_color=\u00bb#afafaf\u00bb background_color_gradient_direction=\u00bb223deg\u00bb background_image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Sin-ti\u0301tulo-2.jpg\u00bb background_enable_image=\u00bbon\u00bb background_blend=\u00bbluminosity\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb23px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#ffffff\u00bb button_border_radius=\u00bb100px\u00bb button_font=\u00bbLato||on||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb header_text_shadow_style__hover=\u00bbnone\u00bb header_text_shadow_style__hover_enabled=\u00bbnone\u00bb header_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb header_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb body_text_shadow_style__hover=\u00bbnone\u00bb body_text_shadow_style__hover_enabled=\u00bbnone\u00bb body_text_shadow_color__hover=\u00bbrgba(0,0,0,0.4)\u00bb body_text_shadow_color__hover_enabled=\u00bbrgba(0,0,0,0.4)\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>Itinerario de Educaci\u00f3n en la Fe<\/p>\n<p>[\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbportada\u00bb _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb||50px\u00bb custom_padding=\u00bb50px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; text_font=\u00bb||||||||\u00bb text_line_height=\u00bb1.3em\u00bb link_font=\u00bb||||||||\u00bb link_text_color=\u00bb#e93b76&#8243; header_font=\u00bb||||||||\u00bb header_text_color=\u00bb#e93b76&#8243; header_2_font=\u00bbLato|700|||||||\u00bb header_2_text_color=\u00bb#e93b76&#8243; header_2_font_size=\u00bb37px\u00bb header_3_font=\u00bb||||||||\u00bb header_3_text_color=\u00bb#e93b76&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h2 style=\"text-align: justify;\"><span style=\"text-align: left;\"><span style=\"font-family: Lato, Helvetica, Arial, Lucida, sans-serif;\"><i>\u00bfQu\u00e9 es el Itinerario de Educaci\u00f3n en la Fe?<\/i><\/span><\/span><span style=\"font-size: 14px; text-align: left; color: #494949; font-weight: 500;\">\u00a0<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">El <strong>Itinerario de Educaci\u00f3n en la Fe (IEF)<\/strong> es un \u201c<strong>proceso educativo<\/strong> <strong>global<\/strong>, seg\u00fan la l\u00f3gica de la <strong>Iniciaci\u00f3n Cristiana<\/strong>, que, teniendo en cuenta la realidad del ser humano en su integridad, gu\u00eda y acompa\u00f1a al adolescente y al joven en el camino hacia la <strong>maduraci\u00f3n cristiana<\/strong> en el mundo de hoy\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Los <strong>objetivos<\/strong> fundamentales que nos proponemos en este itinerario giran en torno <strong>al ser, al conocer, al convivir y al hacer<\/strong>. Queremos que los grupos de fe contribuyan a la <strong>maduraci\u00f3n personal e integral<\/strong> de los participantes, que puedan desarrollar su propia identidad y crecer en vida interior y en vivencia cristiana. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Por este motivo queremos que los grupos contribuyan a que cada participante que recorre el itinerario vaya siendo capaz de dar raz\u00f3n de la propia Fe, que vaya aprendiendo a vivir en sociedad, a relacionarse responsablemente con los dem\u00e1s y a sentirse parte de una <strong>comunidad cristiana<\/strong> de referencia. Que desarrollen la capacidad de servicio a los dem\u00e1s partiendo de las propias capacidades personales. Que sean capaces de cultivar la fortaleza interior, aprendiendo a vivir siendo aut\u00e9nticos oyentes de la Palabra de Dios.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbNoticias de la casa (Texto)\u00bb _builder_version=\u00bb4.17.3&#8243; text_font=\u00bbArial||||\u00bb text_text_color=\u00bb#636a70&#8243; text_font_size=\u00bb22&#8243; text_line_height=\u00bb1.6em\u00bb header_font=\u00bbLato|300|||||||\u00bb header_text_color=\u00bbrgba(81,98,111,0.81)\u00bb header_font_size=\u00bb27px\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb min_height=\u00bb51px\u00bb custom_margin=\u00bb||-62px|||\u00bb custom_padding=\u00bb|||\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>Saludo<\/strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1600 alignleft\" src=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/icono_comfya_prt-min.png\" alt=\"\" width=\"29\" height=\"30\" \/><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb432.1px\u00bb custom_margin=\u00bb8px|auto||auto||\u00bb custom_padding=\u00bb5px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_testimonial author=\u00bbAna Cobos\u00bb job_title=\u00bbCoordinadora del I.E.F.\u00bb portrait_url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2023\/10\/ana-cobo.jpg\u00bb quote_icon_color=\u00bb#e93b76&#8243; quote_icon_background_color=\u00bbRGBA(0,0,0,0)\u00bb portrait_height=\u00bb90px\u00bb _builder_version=\u00bb4.27.0&#8243; author_font=\u00bb|700|on||||||\u00bb position_font=\u00bb||on||||||\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb min_height=\u00bb246.1px\u00bb custom_margin=\u00bb35px|||\u00bb custom_padding=\u00bb||0px|||\u00bb animation_style=\u00bbfade\u00bb hover_enabled=\u00bb0&#8243; box_shadow_style=\u00bbpreset2&#8243; box_shadow_style_image=\u00bbpreset1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\">El <strong>Itinerario de Educaci\u00f3n en la Fe<\/strong> es la propuesta que realizamos para que los j\u00f3venes conozcan a Dios en las diferentes etapas de su vida. Entendemos la Fe como un camino individual pero que se debe de vivir en conjunto, compartiendo las alegr\u00edas y las penas, para tambi\u00e9n poder aprender de las personas que nos rodean. Todo ello vivido desde el <strong>carisma salesiano<\/strong>, haciendo que los distintos grupos IEF terminen sinti\u00e9ndose familia. \u00a1Estaremos m\u00e1s que encantados de recibir a cualquier persona que le apetezca formar parte de nuestros grupos!<\/p>\n<p>[\/et_pb_testimonial][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb custom_margin=\u00bb-114px|auto||auto||\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbLato|300|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_text_color=\u00bb#e93b76&#8243; header_2_font_size=\u00bb37px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00bfCu\u00e1l es tu etapa?<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=\u00bb4.16&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-preComfya.jpg\u00bb title_text=\u00bbLogo preComfya\u00bb url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/precomfya\/\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.17.3&#8243; custom_margin=\u00bb10px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.3&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#4f4f4f\u00bb text_font_size=\u00bb16px\u00bb header_font=\u00bb||||||||\u00bb background_color=\u00bb#f9f9f9&#8243; custom_padding=\u00bb15px|||\u00bb link_option_url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/precomfya\/\u00bb border_radii=\u00bbon|100px|100px|100px|100px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#e93b76&#8243; border_style_all=\u00bbdashed\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><em>De 2\u00ba a 6\u00ba de Primaria<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-Comfya-VSAA-1.png\u00bb title_text=\u00bbLogo Comfya VSAA\u00bb url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/comfya\/\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.17.3&#8243; custom_margin=\u00bb10px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.3&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#4f4f4f\u00bb text_font_size=\u00bb16px\u00bb header_font=\u00bb||||||||\u00bb background_color=\u00bb#f9f9f9&#8243; custom_padding=\u00bb15px|||\u00bb link_option_url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/comfya\/\u00bb border_radii=\u00bbon|100px|100px|100px|100px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#e93b76&#8243; border_style_all=\u00bbdashed\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><em>De 1\u00ba a 4\u00ba de ESO<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-Comfya-dos.png\u00bb title_text=\u00bbLogo Comfya-dos\u00bb url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/comfya2\/\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.17.3&#8243; custom_margin=\u00bb10px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.3&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#4f4f4f\u00bb text_font_size=\u00bb16px\u00bb header_font=\u00bb||||||||\u00bb background_color=\u00bb#f9f9f9&#8243; custom_padding=\u00bb15px|||\u00bb link_option_url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/comfya2\/\u00bb border_radii=\u00bbon|100px|100px|100px|100px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#e93b76&#8243; border_style_all=\u00bbdashed\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><em>1\u00ba y 2\u00ba de Bachillerato<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-Comfya-3.png\u00bb title_text=\u00bbLogo Comfya+\u00bb url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/comfyaplus\/\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.17.3&#8243; custom_margin=\u00bb10px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.3&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#4f4f4f\u00bb text_font_size=\u00bb16px\u00bb header_font=\u00bb||||||||\u00bb background_color=\u00bb#f9f9f9&#8243; custom_padding=\u00bb15px|||\u00bb link_option_url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/comfyaplus\/\u00bb border_radii=\u00bbon|100px|100px|100px|100px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#e93b76&#8243; border_style_all=\u00bbdashed\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><em>De 19 a 23 a\u00f1os<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-Grupos-de-Fe.png\u00bb title_text=\u00bbLogo Grupos de Fe\u00bb url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/grupos-de-fe\/\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.17.3&#8243; custom_margin=\u00bb10px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.17.3&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#4f4f4f\u00bb text_font_size=\u00bb16px\u00bb header_font=\u00bb||||||||\u00bb background_color=\u00bb#f9f9f9&#8243; custom_padding=\u00bb15px|||\u00bb link_option_url=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/grupos-de-fe\/\u00bb border_radii=\u00bbon|100px|100px|100px|100px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#e93b76&#8243; border_style_all=\u00bbdashed\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><em>A partir de 24 a\u00f1os<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00bbon|phone\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb25px||25px|\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb||50px\u00bb disabled=\u00bbon\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbNoticias de la casa (Texto)\u00bb _builder_version=\u00bb4.16&#8243; text_font=\u00bbArial||||\u00bb text_text_color=\u00bb#636a70&#8243; text_font_size=\u00bb22&#8243; text_line_height=\u00bb1.6em\u00bb header_font=\u00bbLato|300|||||||\u00bb header_text_color=\u00bbrgba(81,98,111,0.81)\u00bb header_font_size=\u00bb27px\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>Noticias de Comfya<\/strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1600 alignleft\" src=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/icono_comfya_prt-min.png\" alt=\"\" width=\"29\" height=\"30\" \/><\/strong><\/h1>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb3&#8243; include_categories=\u00bb30&#8243; meta_date=\u00bbj M, Y\u00bb show_author=\u00bboff\u00bb show_categories=\u00bboff\u00bb show_pagination=\u00bboff\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#e93b76&#8243; hover_icon=\u00bb&#xf00e;||fa||900&#8243; disabled_on=\u00bboff|on|off\u00bb admin_label=\u00bbUltimas noticias (Blog)\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#e93b76&#8243; header_font_size=\u00bb16&#8243; header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||||||\u00bb body_font_size=\u00bb12px\u00bb body_line_height=\u00bb1.5em\u00bb meta_font=\u00bb||on||||||\u00bb meta_font_size=\u00bb12&#8243; meta_line_height=\u00bb1.5em\u00bb pagination_font=\u00bb||||||||\u00bb pagination_text_color=\u00bb#000000&#8243; body_font_size_last_edited=\u00bboff|\u00bb pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb0px\u00bb border_color_all_fullwidth=\u00bb#d8d8d8&#8243; box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bbrgba(0,0,0,0.12)\u00bb use_border_color=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blog][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb4&#8243; include_categories=\u00bb30&#8243; meta_date=\u00bbj M, Y\u00bb show_author=\u00bboff\u00bb show_categories=\u00bboff\u00bb show_pagination=\u00bboff\u00bb use_overlay=\u00bbon\u00bb overlay_icon_color=\u00bb#e93b76&#8243; hover_icon=\u00bb&#xf00e;||fa||900&#8243; disabled_on=\u00bbon|off|on\u00bb admin_label=\u00bbUltimas noticias (Blog)\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#e93b76&#8243; header_font_size=\u00bb16&#8243; header_line_height=\u00bb1.2em\u00bb body_font=\u00bb||||\u00bb body_font_size=\u00bb12px\u00bb body_line_height=\u00bb1.5em\u00bb meta_font=\u00bb||on||\u00bb meta_font_size=\u00bb12&#8243; meta_line_height=\u00bb1.5em\u00bb body_font_size_last_edited=\u00bboff|\u00bb pagination_font_size_tablet=\u00bb51&#8243; pagination_line_height_tablet=\u00bb2&#8243; border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb0px\u00bb border_color_all_fullwidth=\u00bb#d8d8d8&#8243; box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bbrgba(0,0,0,0.12)\u00bb use_border_color=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blog][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/noticias\/\u00bb button_text=\u00bbVer todas las noticias\u00bb button_alignment=\u00bbright\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_size=\u00bb19px\u00bb button_text_color=\u00bb#e93b76&#8243; button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#e93b76&#8243; button_border_radius=\u00bb100px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bbdark\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#e93b76&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#e93b76&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb25px||25px|\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bb\u00bfQui\u00e9nes somos? (Texto)\u00bb _builder_version=\u00bb4.16&#8243; text_font=\u00bbArial||||\u00bb text_text_color=\u00bb#636a70&#8243; text_font_size=\u00bb22&#8243; text_line_height=\u00bb1.6em\u00bb header_font=\u00bbLato|300|||||||\u00bb header_text_color=\u00bbrgba(81,98,111,0.81)\u00bb header_font_size=\u00bb27px\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>Para saber m\u00e1s&#8230;<\/strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2640 alignleft\" src=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/don-bosco.png\" alt=\"\" width=\"29\" height=\"30\" \/><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb25px||30px|\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbComfya\u00bb url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/que-es\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe066;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb59px\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh2&#8243; header_font=\u00bb||||||||\u00bb header_text_color=\u00bb#e93b76&#8243; header_font_size=\u00bb19px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb animation=\u00bboff\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bbrgba(99,106,112,0.44)\u00bb icon_font_size=\u00bb59px\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bbrgba(99,106,112,0.44)\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbItinerario de Educaci\u00f3n en la Fe\u00bb url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/ief\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe01c;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb59px\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh2&#8243; header_font=\u00bb||||||||\u00bb header_text_color=\u00bb#e93b76&#8243; header_font_size=\u00bb19px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb animation=\u00bboff\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bbrgba(99,106,112,0.44)\u00bb icon_font_size=\u00bb59px\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bbrgba(99,106,112,0.44)\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMovimiento Juvenil Salesiano\u00bb url=\u00bbhttps:\/\/alicante.salesianos.edu\/mjs\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe08b;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb59px\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh2&#8243; header_font=\u00bb||||||||\u00bb header_text_color=\u00bb#e93b76&#8243; header_font_size=\u00bb19px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb animation=\u00bboff\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bbrgba(99,106,112,0.44)\u00bb icon_font_size=\u00bb59px\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bbrgba(99,106,112,0.44)\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbProyecto Educativo Pastoral\u00bb url=\u00bbhttp:\/\/alicante.salesianos.edu\/peps\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb59px\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh2&#8243; header_font=\u00bb||||||||\u00bb header_text_color=\u00bb#e93b76&#8243; header_font_size=\u00bb19px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb animation=\u00bboff\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bbrgba(99,106,112,0.44)\u00bb icon_font_size=\u00bb59px\u00bb use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bbrgba(99,106,112,0.44)\u00bb circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bbon|on|on\u00bb module_id=\u00bbDestacado\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb25px||20px|\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbDestacado (Texto)\u00bb _builder_version=\u00bb4.16&#8243; text_font=\u00bbArial||||\u00bb text_text_color=\u00bb#636a70&#8243; text_font_size=\u00bb22&#8243; text_line_height=\u00bb1.6em\u00bb header_font=\u00bbLato|300|||||||\u00bb header_text_color=\u00bbrgba(81,98,111,0.81)\u00bb header_font_size=\u00bb27px\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>Destacado<\/strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2640 alignleft\" src=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/destacados.png\" alt=\"\" width=\"29\" height=\"30\" \/><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; custom_padding_last_edited=\u00bboff|desktop\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb25px||60px|\u00bb custom_padding_tablet=\u00bb0px||0px|\u00bb custom_padding_phone=\u00bb0px||0px|\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/Logo-Comfya-BASICO.png\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbLato|300|||||||\u00bb header_4_text_color=\u00bb#e93b76&#8243; header_4_font_size=\u00bb32px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><strong>#Comfya<\/strong>Colegio<\/h4>\n<p><em>Haz click en tu etapa de Comfya para descargar la <strong>ficha de inscripci\u00f3n<\/strong>.<\/em><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-pre-comfya-adb\/?wpdmdl=2785&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbPre-Comfya\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-comfya-1-adb\/?wpdmdl=2786&#038;refresh=5d80c50d9c96d1568720141&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbComfya 1&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-comfya-2-adb\/?wpdmdl=2787&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbComfya 2&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-comfya-3-adb\/?wpdmdl=2788&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbComfya 3&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-comfya-4-adb\/?wpdmdl=2789&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbComfya 4&#8243; button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-comfya-plus-adb\/?wpdmdl=2790&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbComfya +\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/comfya-adb-wpdmdl3586refresh5d81ec0b5bfab1568795659ficha-de-inscripcion-comfya-adb\/?wpdmdl=3586&#038;refresh=5d8208c17a7f91568803009&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbComfya + +\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_text disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbLato|300|||||||\u00bb header_4_text_color=\u00bb#e93b76&#8243; header_4_font_size=\u00bb32px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><strong>#Comfya<\/strong>Parroquia<\/h4>\n<p><em>Haz click en tu etapa de Comfya para descargar la <strong>ficha de inscripci\u00f3n<\/strong>.<\/em><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-pre-comfya-ama\/?wpdmdl=3177&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbPre-Comfya\u00bb button_alignment=\u00bbleft\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/download\/ficha-de-inscripcion-comfya-ama\/?wpdmdl=3176&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbComfya\u00bb button_alignment=\u00bbleft\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/tmp_21_enero_2020_Calendario-KTQSS-2020-21-2.jpg\u00bb title_text=\u00bbtmp_21_enero_2020_Calendario KTQSS 2020-21-2&#8243; show_in_lightbox=\u00bbon\u00bb align=\u00bbcenter\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbLato|300|||||||\u00bb header_4_text_color=\u00bb#e93b76&#8243; header_4_font_size=\u00bb32px\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><strong>Catequesis de 1\u00aa Comuni\u00f3n<\/strong><\/h4>\n<p style=\"text-align: justify\">El d\u00eda de inicio de la Catequesis han de venir con el libro correspondiente seg\u00fan el curso:<\/p>\n<ul>\n<li style=\"text-align: justify\"><strong>2\u00ba de Primaria\u00a0<\/strong><u>\u00ab<strong>El\u00a0Despertar Religioso\u00bb<\/strong><\/u><strong>,\u00a0<\/strong>2 libros, el de Padres y el del ni\u00f1o\/a. Se inicia el 28 de octubre. Es Catequesis Familiar, presencial para los padres; para los ni\u00f1os, NO. Se utiliza la iglesia por su amplio espacio y un mi\u00e9rcoles al mes.<\/li>\n<li style=\"text-align: justify\"><strong>3\u00ba de Primaria<\/strong>, que ya han hecho la Catequesis de 2\u00ba \u00a0<strong><u>\u00abJes\u00fas es nuestro amigo\u00bb<\/u>. <\/strong>La inician el 20 de octubre. Al ser muchos se har\u00e1n dos turnos que asistir\u00e1n alternativamente los martes.<\/li>\n<li style=\"text-align: justify\"><strong>4\u00ba de Primaria\u00a0<\/strong>que ya han completado las Catequesis de 3\u00ba y 2\u00ba, el libro es <strong><u>\u00abSomos amigos de Jes\u00fas\u00bb<\/u> <\/strong>la inician el d\u00eda 15 de octubre los jueves.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_toggle title=\u00bbGrupos 3\u00ba de Primaria\u00bb open_toggle_text_color=\u00bb#e93b76&#8243; open_toggle_background_color=\u00bbrgba(0,0,0,0)\u00bb closed_toggle_text_color=\u00bb#e93b76&#8243; closed_toggle_background_color=\u00bbrgba(0,0,0,0)\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; title_text_color=\u00bb#e93b76&#8243; title_level=\u00bbh4&#8243; title_font=\u00bbLato||||||||\u00bb title_text_align=\u00bbleft\u00bb title_font_size=\u00bb18px\u00bb title_line_height=\u00bb1.3em\u00bb closed_title_font=\u00bbLato||||||||\u00bb closed_title_text_align=\u00bbleft\u00bb closed_title_font_size=\u00bb18px\u00bb closed_title_line_height=\u00bb1.3em\u00bb body_text_color=\u00bb#51626f\u00bb text_orientation=\u00bbleft\u00bb max_width=\u00bb700px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb border_width_all=\u00bb0px\u00bb border_width_top=\u00bb1px\u00bb border_color_top=\u00bbrgba(81,98,111,0.27)\u00bb border_style_top=\u00bbdashed\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/tmp_Grupos-de-3o-KTQSS-min.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/tmp_Grupos-de-3o-KTQSS-min.png\" width=\"1043\" height=\"540\" alt=\"\" class=\"wp-image-3773 aligncenter size-full\" \/><\/a><\/p>\n<p>[\/et_pb_toggle][et_pb_divider color=\u00bb#51626f\u00bb divider_style=\u00bbdashed\u00bb divider_position=\u00bbcenter\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-7px||||false|false\u00bb custom_padding=\u00bb||||false|false\u00bb filter_opacity=\u00bb30%\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/image.jimcdn.com\/app\/cms\/image\/transf\/dimension=1000&#215;10000:format=png\/path\/se98dcd3f9abef28a\/image\/i2f62ff508ac1b888\/version\/1515960805\/image.png\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbLato|300|||||||\u00bb header_4_text_color=\u00bb#e93b76&#8243; header_4_font_size=\u00bb32px\u00bb custom_padding=\u00bb40px|||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><strong>Fiesta de Mar\u00eda Auxiliadora<\/strong><\/h4>\n<p><i>\u00a1Disfruta de la celebraci\u00f3n y de la cena con tus compa\u00f1eros\/as de Comfya! \u00a1Ap\u00fantate ya!<\/i><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/forms.gle\/nsENfaQm7aX74LKh8&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbInscripci\u00f3n online\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#xe07e;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_color__hover=\u00bb#cccccc\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/fiesta-maria-auxiliadora\/\u00bb button_text=\u00bbM\u00e1s informaci\u00f3n\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x54;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_color__hover=\u00bb#cccccc\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/www.salesianos.edu\/Archivos\/Galerias\/Mis_Galerias\/PASCUA\/20190226CartelPascua.png\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb-12px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbLato|300|||||||\u00bb header_4_text_color=\u00bb#06559b\u00bb header_4_font_size=\u00bb32px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><strong>#PascuaJoven<\/strong><\/h4>\n<p><em>Convivencia para j\u00f3venes en el Colegio Don Bosco los d\u00edas <strong>19 y 20 de abril<\/strong>.<\/em><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttp:\/\/alicante.salesianos.edu\/wp-content\/uploads\/2019\/03\/tmp_informacion_pascuajoven2019.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbInformaci\u00f3n y horario\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#06559b\u00bb button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x69;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_color__hover=\u00bb#013f75&#8243;][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfbxc8oHy6WJaVk_iaGvgHBfaYZq-WdVKa4QQEAwlnX2lVBFw\/viewform\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbInscripci\u00f3n online\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#06559b\u00bb button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#xe07e;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_color__hover=\u00bb#013f75&#8243;][\/et_pb_button][et_pb_divider color=\u00bb#c6c6c6&#8243; divider_style=\u00bbdashed\u00bb divider_position=\u00bbcenter\u00bb divider_weight=\u00bb1px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00bb4.16&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbLato|300|||||||\u00bb header_4_text_color=\u00bb#06559b\u00bb header_4_font_size=\u00bb32px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><strong>#PascuaFamiliar<\/strong><\/h4>\n<p><em>Vive la Pascua en familia los d\u00edas <strong>18, 19 y 20 de abril<\/strong> en el Colegio Don Bosco<\/em><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttp:\/\/alicante.salesianos.edu\/wp-content\/uploads\/2019\/03\/tmp_informacion_pascuajoven2019.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbInformaci\u00f3n y horario\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#06559b\u00bb button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x69;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_color__hover=\u00bb#013f75&#8243;][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfbxc8oHy6WJaVk_iaGvgHBfaYZq-WdVKa4QQEAwlnX2lVBFw\/viewform\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbInscripci\u00f3n online\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#06559b\u00bb button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#xe07e;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_color__hover=\u00bb#013f75&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; header_font=\u00bb||||||||\u00bb header_4_font=\u00bbLato|300|||||||\u00bb header_4_text_color=\u00bb#e93b76&#8243; header_4_font_size=\u00bb32px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><strong>\u00a1Nos vamos a ver el Musical 33!<\/strong><\/h4>\n<p><i>Ven a ver este pedazo de musical en Madrid con Comfya. \u00a1No te lo pienses m\u00e1s y ap\u00fantate!<\/i><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/wp-content\/uploads\/sites\/10\/2018\/11\/tmp_inscripcion-musical-33-min.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbDescargar inscripci\u00f3n\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e93b76&#8243; button_bg_blend=\u00bboverlay\u00bb button_border_width=\u00bb0px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x69;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_color__hover=\u00bb#51626f\u00bb][\/et_pb_button][et_pb_image src=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/wp-content\/uploads\/sites\/10\/2018\/11\/tmp_musical33-min.jpg\u00bb url=\u00bbhttps:\/\/alicante.salesianos.edu\/comfya\/wp-content\/uploads\/sites\/10\/2018\/11\/tmp_inscripcion-musical-33-min.pdf\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bb\u00bb align_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb80px||25px|||\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb||0px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbRedes sociales (Texto)\u00bb _builder_version=\u00bb4.16&#8243; text_font=\u00bbArial||||\u00bb text_text_color=\u00bb#636a70&#8243; text_font_size=\u00bb22&#8243; text_line_height=\u00bb1.6em\u00bb header_font=\u00bbLato|300|||||||\u00bb header_text_color=\u00bbrgba(81,98,111,0.81)\u00bb header_font_size=\u00bb27px\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>Redes sociales<\/strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2640 alignleft\" src=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/redes_sociales.png\" alt=\"\" width=\"29\" height=\"30\" \/><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_social_media_follow _builder_version=\u00bb4.16&#8243; border_radii=\u00bbon|100%|100%|100%|100%\u00bb link_shape=\u00bbcircle\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/SalesianosALC\/\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#4267b2&#8243; background_enable_color=\u00bbon\u00bb bg_color=\u00bb#3b5998&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbtwitter\u00bb url=\u00bbhttps:\/\/twitter.com\/SalesianosALC\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#1da1f2&#8243; background_enable_color=\u00bbon\u00bb bg_color=\u00bb#00aced\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/salesianosalc\/\u00bb _builder_version=\u00bb4.16&#8243; background_enable_color=\u00bboff\u00bb background_image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/instagram_color_background.jpg\u00bb background_enable_image=\u00bbon\u00bb background_size=\u00bbcontain\u00bb bg_color=\u00bb#517fa4&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbyoutube\u00bb url=\u00bbhttps:\/\/www.youtube.com\/user\/SalesianosALC\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ff0000&#8243; background_enable_color=\u00bbon\u00bb bg_color=\u00bb#a82400&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]youtube[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_code disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"g-ytsubscribe\" data-channel=\"SalesianosALC\" data-layout=\"default\" data-count=\"default\"><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0px||30px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_code admin_label=\u00bbTwitter (C\u00f3digo)\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<a class=\"twitter-timeline\" data-lang=\"es\" data-width=\"750\" data-height=\"582\" href=\"https:\/\/twitter.com\/SalesianosALC\"><\/a> [\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider show_divider=\u00bboff\u00bb disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.16&#8243; height=\u00bb7px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_code disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbFacebook (C\u00f3digo)\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][fb_plugin page href=https:\/\/www.facebook.com\/salesianosALC hide-cover=true tabs=timeline small-header=true show-facepile=false width=750][\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_code admin_label=\u00bbInstagram (C\u00f3digo)\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][instagram-feed][\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb25px||25px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbSalesianos (Texto)\u00bb _builder_version=\u00bb4.16&#8243; text_font=\u00bbArial||||\u00bb text_text_color=\u00bb#636a70&#8243; text_font_size=\u00bb22&#8243; text_line_height=\u00bb1.6em\u00bb header_font=\u00bbLato|300|||||||\u00bb header_text_color=\u00bbrgba(81,98,111,0.81)\u00bb header_font_size=\u00bb27px\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong>Salesianos<\/strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2640 alignleft\" src=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/enlaces_salesianos.png\" alt=\"\" width=\"29\" height=\"30\" \/><\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_6,1_6,1_6,1_6,1_6,1_6&#8243; column_padding_mobile=\u00bbon\u00bb module_id=\u00bbportada-web-salesianas\u00bb module_class=\u00bb et_pb_row_fullwidth\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb94%\u00bb width_tablet=\u00bb80%\u00bb width_phone=\u00bb\u00bb width_last_edited=\u00bbon|desktop\u00bb max_width=\u00bb94%\u00bb max_width_tablet=\u00bb80%\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|desktop\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb25px|||\u00bb make_fullwidth=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.16&#8243; background_position=\u00bbtop_left\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb url=\u00bbhttp:\/\/sdb.org\/es\/\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/01_SDBORG.png\u00bb alt=\u00bbSalesianos en el mundo\u00bb admin_label=\u00bbSDB_org\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbcenter\u00bb animation_style=\u00bbbounce\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]En el mundo<br \/>\n[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb url=\u00bbhttp:\/\/www.donbosco.es\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/02_DBES.png\u00bb alt=\u00bbSalesianos en Espa\u00f1a\u00bb admin_label=\u00bbDonBosco_ES\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbcenter\u00bb animation_style=\u00bbbounce\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]En Espa\u00f1a<br \/>\n[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb url=\u00bbhttp:\/\/www.salesianos.edu\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/03_smxedu.png\u00bb admin_label=\u00bbInspector\u00eda\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbcenter\u00bb animation_style=\u00bbbounce\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]En la Inspector\u00eda<br \/>\n[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb url=\u00bbhttp:\/\/www.infoans.org\/es\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/04_ans.png\u00bb admin_label=\u00bbANS_info\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbcenter\u00bb animation_style=\u00bbbounce\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Agencia noticias<br \/>\n[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb url=\u00bbhttp:\/\/boletin-salesiano.com\/\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/05_boletins.png\u00bb admin_label=\u00bbBoletinSalesiano\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbcenter\u00bb animation_style=\u00bbbounce\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Bolet\u00edn Salesiano<br \/>\n[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb url=\u00bbhttp:\/\/www.salesianos.info\/\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/06_salesinfo.png\u00bb admin_label=\u00bbInspector\u00eda\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb text_orientation=\u00bbcenter\u00bb animation_style=\u00bbbounce\u00bb animation=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]Salesianos INFO<br \/>\n[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ven y ver\u00e1s&#8230;Mismas raicesItinerario de Educaci\u00f3n en la Fe \u00bfQu\u00e9 es el Itinerario de Educaci\u00f3n en la Fe?\u00a0 El Itinerario de Educaci\u00f3n en la Fe (IEF) es un \u201cproceso educativo global, seg\u00fan la l\u00f3gica de la Iniciaci\u00f3n Cristiana, que, teniendo en cuenta la realidad del ser humano en su integridad, gu\u00eda y acompa\u00f1a al adolescente [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IEF | COMFYA - Itinerario Educaci\u00f3n en la Fe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IEF | COMFYA - Itinerario Educaci\u00f3n en la Fe\" \/>\n<meta property=\"og:description\" content=\"Ven y ver\u00e1s...Mismas raicesItinerario de Educaci\u00f3n en la Fe \u00bfQu\u00e9 es el Itinerario de Educaci\u00f3n en la Fe?\u00a0 El Itinerario de Educaci\u00f3n en la Fe (IEF) es un \u201cproceso educativo global, seg\u00fan la l\u00f3gica de la Iniciaci\u00f3n Cristiana, que, teniendo en cuenta la realidad del ser humano en su integridad, gu\u00eda y acompa\u00f1a al adolescente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/\" \/>\n<meta property=\"og:site_name\" content=\"Itinerario Educaci\u00f3n en la Fe\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T16:28:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/icono_comfya_prt-min.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"50 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/\",\"url\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/\",\"name\":\"IEF | COMFYA - Itinerario Educaci\u00f3n en la Fe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/05\\\/icono_comfya_prt-min.png\",\"datePublished\":\"2022-05-11T11:00:17+00:00\",\"dateModified\":\"2024-10-01T16:28:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/05\\\/icono_comfya_prt-min.png\",\"contentUrl\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/05\\\/icono_comfya_prt-min.png\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IEF | COMFYA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/#website\",\"url\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/\",\"name\":\"Itinerario Educaci\u00f3n en la Fe\",\"description\":\"Otro sitio m\u00e1s de Salesianos San Antonio Abad Valencia sitios\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valenciasaa.salesianos.edu\\\/iefcomfya\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IEF | COMFYA - Itinerario Educaci\u00f3n en la Fe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/","og_locale":"es_ES","og_type":"article","og_title":"IEF | COMFYA - Itinerario Educaci\u00f3n en la Fe","og_description":"Ven y ver\u00e1s...Mismas raicesItinerario de Educaci\u00f3n en la Fe \u00bfQu\u00e9 es el Itinerario de Educaci\u00f3n en la Fe?\u00a0 El Itinerario de Educaci\u00f3n en la Fe (IEF) es un \u201cproceso educativo global, seg\u00fan la l\u00f3gica de la Iniciaci\u00f3n Cristiana, que, teniendo en cuenta la realidad del ser humano en su integridad, gu\u00eda y acompa\u00f1a al adolescente [&hellip;]","og_url":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/","og_site_name":"Itinerario Educaci\u00f3n en la Fe","article_modified_time":"2024-10-01T16:28:58+00:00","og_image":[{"url":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/icono_comfya_prt-min.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"50 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/","url":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/","name":"IEF | COMFYA - Itinerario Educaci\u00f3n en la Fe","isPartOf":{"@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/#primaryimage"},"image":{"@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/#primaryimage"},"thumbnailUrl":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/icono_comfya_prt-min.png","datePublished":"2022-05-11T11:00:17+00:00","dateModified":"2024-10-01T16:28:58+00:00","breadcrumb":{"@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/#primaryimage","url":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/icono_comfya_prt-min.png","contentUrl":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-content\/uploads\/sites\/9\/2022\/05\/icono_comfya_prt-min.png","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/"},{"@type":"ListItem","position":2,"name":"IEF | COMFYA"}]},{"@type":"WebSite","@id":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/#website","url":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/","name":"Itinerario Educaci\u00f3n en la Fe","description":"Otro sitio m\u00e1s de Salesianos San Antonio Abad Valencia sitios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":11,"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":173,"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/pages\/13\/revisions\/173"}],"wp:attachment":[{"href":"https:\/\/valenciasaa.salesianos.edu\/iefcomfya\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}